{"id":25528,"date":"2020-11-30T17:02:21","date_gmt":"2020-11-30T09:02:21","guid":{"rendered":"https:\/\/flydesk.com\/?p=25528"},"modified":"2023-01-11T11:21:55","modified_gmt":"2023-01-11T03:21:55","slug":"best-remote-team-building-tools","status":"publish","type":"post","link":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/","title":{"rendered":"Meilleurs outils de consolidation d&#039;\u00e9quipe \u00e0 distance"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La mont\u00e9e en puissance du travail \u00e0 distance n\u00e9cessite de trouver de nouvelles m\u00e9thodes de consolidation d&#039;\u00e9quipe, ce qui ne sera pas une t\u00e2che facile lorsque l&#039;\u00e9quipe est r\u00e9partie sur plusieurs sites. Dans cet article, nous souhaitons vous faire part de certains outils r\u00e9els que vous pouvez utiliser, ainsi que des activit\u00e9s amusantes et r\u00e9alisables pour les \u00e9quipes virtuelles de toutes tailles. Choisissez judicieusement ce qui vous convient!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Brise-glace virtuels<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Voici trois brise-glace avec lesquels vous pouvez commencer.\u00a0<\/span><\/p>\n<h3><b>1. Brise-glace virtuel Rose \/ Thorn<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Ce brise-glace ouvre la voie \u00e0 des bribes de la vie quotidienne de chaque membre. C&#039;est l&#039;occasion de lib\u00e9rer un peu de stress ou de c\u00e9l\u00e9brer certaines victoires. Chaque membre a l&#039;occasion de raconter pendant une minute sa \u00abrose\u00bb (situations privil\u00e9gi\u00e9es telles que r\u00e9alisations, remboursements, etc.) ainsi que son \u00ab\u00e9pine\u00bb (obstacles, d\u00e9fis, etc.). \u00abUne rose peut \u00eatre li\u00e9e au travail ou non avec son \u00e9pine.\u00bb.<\/span><\/p>\n<h3><b>2. Brise-glace virtuel Crime Junkie<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Quant \u00e0 celui-ci, vous aurez besoin<\/span> <a href=\"https:\/\/try.outbackteambuilding.com\/virtual-clue-murder-mystery-team-building\/\">Clue Virtual Murder Mystery<\/a><span style=\"font-weight: 400;\"> pour une application Web prise en charge. Comme son nom l&#039;indique, ceux qui envisagent de se joindre pourraient aussi bien convoquer leurs d\u00e9tectives int\u00e9rieurs parce qu&#039;ils r\u00e9soudront un crime, mais seulement pendant dix \u00e0 quinze minutes. Divisez l&#039;\u00e9quipe en deux ou trois groupes et envoyez le <\/span><a href=\"https:\/\/try.outbackteambuilding.com\/virtual-clue-murder-mystery-team-building\/\"><span style=\"font-weight: 400;\">lien<\/span><\/a><span style=\"font-weight: 400;\"> pour chaque. Quand c&#039;est fini, c\u00e9l\u00e9brez le moment \u00abaha\u00bb du groupe qui a gagn\u00e9. Ceux qui perdent pourraient \u00e9valuer ce que pourrait \u00eatre ce quelque chose qui ne leur a pas permis de remporter le troph\u00e9e.<\/span><\/p>\n<h3><b>3. Nommez cette chanson Emoji Titre Virtual Icebreaker<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Dans ce jeu, les \u00e9mojis sont utilis\u00e9s comme titres de chansons, pas lorsque vous \u00eates exasp\u00e9r\u00e9 ou ravi. Utilisez une plate-forme de messagerie de groupe o\u00f9 tout le monde joue et c&#039;est \u00e0 vous de savoir comment identifier qui joue en premier, mais chaque membre devrait disposer de trois minutes pour deviner le titre de la derni\u00e8re chanson que `` il &#039;&#039; avait \u00e9cout\u00e9 laquelle le &#039; \u00e7a devrait se cacher \u00e0 travers les emojis. Le groupe ou l&#039;individu avec les suppositions les plus correctes gagne. Par exemple:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">?? (Ocean Eyes - Billie Eilish)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">??? (Lumi\u00e8res aveuglantes - The Weeknd)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">? (Poker Face - Lady Gaga)<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Si vous cherchez plus de brise-glace, <a href=\"https:\/\/snacknation.com\/blog\/virtual-team-building\/\">assurez-vous de consulter \u00e9galement l&#039;article de SnackNation<\/a>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Applications de chasse au tr\u00e9sor<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Qui n&#039;aime pas la chasse au tr\u00e9sor classique, non? Gr\u00e2ce \u00e0 ces applications, vous pouvez toujours jouer virtuellement \u00e0 votre chasse au tr\u00e9sor pr\u00e9f\u00e9r\u00e9e. Lisez la suite pour les apprendre.<\/span><\/p>\n<h3><b>1. GooseChase<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Celui-ci vous permet de choisir parmi une \u00abbanque de missions\u00bb existante ou d&#039;en cr\u00e9er une nouvelle \u00e0 votre go\u00fbt (si vous \u00eates le cr\u00e9ateur de la chasse). Fixez une heure apr\u00e8s la cr\u00e9ation de la mission. La t\u00e2che varie et peut devenir intense car elle peut impliquer des inconnus al\u00e9atoires avec lesquels les joueurs doivent prendre une photo. Au fur et \u00e0 mesure que nous y sommes, les r\u00e9ponses sont soumises en photos via l&#039;application. L&#039;\u00e9quipe ou l&#039;individu avec le plus de points l&#039;emporte. &quot;Le jeu est gratuit si vous l&#039;utilisez pour organiser une petite chasse en \u00e9quipe, et GooseChase propose des forfaits payants pour les grands groupes ou les entreprises.&quot;<\/span><\/p>\n<p>T\u00e9l\u00e9chargez gratuitement l&#039;application:<a href=\"https:\/\/itunes.apple.com\/ca\/app\/goosechase\/id437330879\"> iOS<\/a> |<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.goosechaseadventures.goosechase\"> Android<\/a><\/p>\n<h3><b>2. Locandie<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Locandy vous propose une t\u00e2che toute faite mais la torsion est assez int\u00e9ressante. Les t\u00e2ches ressemblent plus \u00e0 des qu\u00eates et vous devez faire des choix. &quot;L&#039;histoire change et \u00e9volue en fonction de ce que vous choisissez de faire.&quot; Jouer \u00e0 ce jeu vous permet d&#039;explorer votre environnement et ainsi de d\u00e9couvrir de superbes endroits tout en profitant de l&#039;interaction avec l&#039;\u00e9quipe, m\u00eame lorsque vous \u00eates seul. L&#039;application et tous les jeux inclus sont gratuits. De plus, vous n&#039;aurez besoin d&#039;aucune connexion Internet apr\u00e8s l&#039;avoir install\u00e9 sur votre t\u00e9l\u00e9phone. Activez simplement votre GPS et explorez!<\/span><\/p>\n<p>T\u00e9l\u00e9chargez gratuitement l&#039;application:<a href=\"https:\/\/itunes.apple.com\/at\/app\/locandy\/id789268894\"> iOS<\/a> |<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.locandy.app.locandy\"> Android<\/a><\/p>\n<h3><b>3. Huntzz<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Cette application propose \u00e9galement des t\u00e2ches pr\u00eates \u00e0 l&#039;emploi, mais si vous pr\u00e9f\u00e9rez cr\u00e9er, vous \u00eates libre de le faire. Le sentiment d&#039;un charognard est assez vivant avec ce jeu car il vous fournit une carte ancienne que vous allez utiliser pour vous promener dans la zone de chasse. Si vous vous trouvez dans un endroit o\u00f9 il a d\u00e9j\u00e0 \u00e9t\u00e9 utilis\u00e9 pour une chasse, vous pouvez choisir de jouer au jeu cr\u00e9\u00e9 pour cet endroit sp\u00e9cifique. Ce jeu se concentre principalement sur le tourisme car vous devez trouver des indices appel\u00e9s \u00abparchemins\u00bb dispers\u00e9s dans la zone, ce qui pourrait vous conduire \u00e0 des points de rep\u00e8re impressionnants et \u00e0 des expositions assez int\u00e9ressantes. Cependant, certains jeux ne sont pas gratuits. Il existe \u00e9galement une option pour obtenir un acc\u00e8s complet \u00e0 tous les jeux payants de l&#039;application.<\/span><\/p>\n<p>T\u00e9l\u00e9chargez l&#039;application gratuitement : iOS | Android<\/p>\n<h3><b>4. Scavify<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Scavify am\u00e8ne le jeu \u00e0 un niveau sup\u00e9rieur. La t\u00e2che de cette chasse n\u00e9cessite de prendre des photos et des vid\u00e9os \u00e0 diff\u00e9rents endroits, de r\u00e9pondre \u00e0 des questions de type quiz, de r\u00e9soudre des \u00e9nigmes et de scanner les codes QR trouv\u00e9s \u00e0 certains endroits. Si vous avez peur que ce soit trop pour un groupe de trois membres, vous devez vous calmer. Scavify propose diff\u00e9rentes chasses en fonction du nombre d&#039;individus dans le groupe. L&#039;inconv\u00e9nient, cependant, n&#039;inclut pas une option d&#039;essai gratuite. Pour les petits groupes de 10 joueurs, les packages personnels commencent \u00e0 $29.<\/span><\/p>\n<p>T\u00e9l\u00e9chargez gratuitement l&#039;application:<a href=\"https:\/\/itunes.apple.com\/us\/app\/scavify\/id799741525?mt=8\"> iOS<\/a> |<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.scavify.app\"> Android<\/a><\/p>\n<h3><b>5. G\u00e9ocaching<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">L&#039;approche du g\u00e9ocaching est plut\u00f4t amusante! Ce jeu oblige les utilisateurs \u00e0 cr\u00e9er d&#039;abord des \u00abcaches\u00bb et \u00e0 les remplir d&#039;\u00e9l\u00e9ments, puis \u00e0 les cacher o\u00f9 ils le souhaitent. Les utilisateurs t\u00e9l\u00e9chargent ensuite les coordonn\u00e9es GPS sur le Web et laissent les joueurs trouver les caches. Si un cache est trouv\u00e9, le joueur peut soit le remplacer par un objet de valeur \u00e9gale ou sup\u00e9rieure et r\u00e9clamer ce qui a \u00e9t\u00e9 trouv\u00e9. \u00abLes caches diff\u00e8rent en fonction de leur taille, de leur distance et de leur difficult\u00e9.\u00bb Pour une carte de cache mise \u00e0 jour, acc\u00e9dez gratuitement \u00e0 n&#039;importe quel site Web de g\u00e9ocaching ou \u00e0 n&#039;importe quelle application de g\u00e9ocaching.<\/span><\/p>\n<p>T\u00e9l\u00e9chargez gratuitement l&#039;application:<a href=\"https:\/\/apps.apple.com\/us\/app\/geocaching\/id329541503\"> iOS<\/a> |<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.groundspeak.geocaching.intro\"> Android<\/a><\/p>\n<h3><b>6. Chasse au tr\u00e9sor Emoji de Google\u00a0<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Celui-ci est un exercice parfait pour une observation rapide car vous \u00eates charg\u00e9 de rep\u00e9rer pendant 20 secondes, tout ce que Google vous demande de trouver. \u00abUn r\u00e9seau neuronal\u2026 essaiera d&#039;identifier ce que vous tenez devant votre cam\u00e9ra.\u00bb Pour d\u00e9marrer le jeu, vous devez cliquer sur ce lien, <\/span><a href=\"https:\/\/emojiscavengerhunt.withgoogle.com\/\">emojiscavengerhunt.withgoogle.com<\/a><span style=\"font-weight: 400;\">. Vous aurez 20 secondes pour terminer chaque t\u00e2che. Vous pouvez m\u00eame activer le son lorsque Google identifie les \u00e9l\u00e9ments pr\u00e9sent\u00e9s sur l&#039;appareil photo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Id\u00e9es amusantes de jeux de vid\u00e9oconf\u00e9rence<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Qu&#039;en est-il de curieux jeux de conf\u00e9rence t\u00e9l\u00e9phonique? Voil\u00e0 quelque:<\/span><\/p>\n<h3><b>1. Trois petits cochons<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Les participants sont charg\u00e9s de construire l&#039;enclos \u00e0 porcs le plus solide possible pendant seulement trois minutes. Les mat\u00e9riaux ne devraient \u00eatre qu&#039;\u00e0 leur port\u00e9e. Ce jeu est encore meilleur si vous pouvez regrouper quelques co\u00e9quipiers au m\u00eame endroit. Apr\u00e8s trois minutes, ces enclos pour porcs doivent \u00eatre test\u00e9s en soufflant de l&#039;air dessus. Les niveaux de coup devraient commencer \u00e0 1 \u00e9tant le plus faible et devraient monter \u00e0 10 \u00e9tant le plus fort. Les stylos qui sont rest\u00e9s jusqu&#039;au niveau 10 marquent un point.<\/span><\/p>\n<h3><b>2. Affaires de 10 minutes<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Exercez les comp\u00e9tences entrepreneuriales et de r\u00e9flexion parmi les membres de l&#039;\u00e9quipe avec ce jeu sain. Cela n\u00e9cessite des \u00e9quipes de quatre \u00e0 cinq membres chacune. Ces \u00e9quipes devraient ensuite organiser des conf\u00e9rences t\u00e9l\u00e9phoniques distinctes \u00abpour d\u00e9velopper un nouveau concept commercial et un nouveau pitch\u00bb, mais seulement pendant 10 minutes. Un th\u00e8me peut \u00eatre propos\u00e9, par exemple &quot;r\u00e9novation d&#039;un h\u00f4tel \u00e0 petit budget&quot; ou &quot;meilleur cadeau de No\u00ebl $5 \u00e0 emporter \u00e0 la maison pour les employ\u00e9s&quot;. Les \u00e9quipes doivent ensuite pr\u00e9senter leurs id\u00e9es apr\u00e8s 10 minutes. L&#039;\u00e9quipe qui a la meilleure id\u00e9e sera r\u00e9compens\u00e9e et pendant que vous y \u00eates, vous pouvez inclure un rafra\u00eechissement ou une inculquer la valeur de la prise de d\u00e9cision et de l&#039;esprit d&#039;entreprise.<\/span><\/p>\n<h3><b>3. Qu&#039;y a-t-il sur mon bureau?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Si vous \u00eates le chef d&#039;\u00e9quipe et que vous voulez cr\u00e9er un lien entre les membres, vous pourriez aussi avoir besoin d&#039;essayer ce jeu. Tout ce que vous avez \u00e0 faire est de demander \u00e0 chaque membre d&#039;envoyer une photo de son bureau sur un espace partag\u00e9 afin que chaque membre puisse jeter un coup d&#039;\u0153il et deviner \u00e0 qui appartient le bureau par la connaissance pr\u00e9alable de chaque membre les uns avec les autres. Cela pourrait \u00e9galement aider chaque membre \u00e0 trouver un terrain d&#039;entente entre eux, ce qui aiderait ensuite l&#039;\u00e9quipe \u00e0 obtenir de meilleurs travaux et r\u00e9sultats.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Qui a dit que la consolidation d&#039;\u00e9quipe \u00e0 distance ne pouvait pas \u00eatre amusante et engageante? La technologie a prouv\u00e9 que la distance n&#039;est pas un obstacle! Chez FLYDESK, nous croyons en l&#039;importance de rompre votre routine et de changer r\u00e9guli\u00e8rement d&#039;espace de travail pour maintenir votre \u00e9nergie et votre motivation. Si vous vous sentez encore trop isol\u00e9 au travail \u00e0 domicile ou si vous souhaitez simplement changer d&#039;environnement de bureau, <\/span><a href=\"https:\/\/flydesk.com\/fr\/workspace\/\"><span style=\"font-weight: 400;\">dirigez-vous vers votre espace de coworking le plus proche<\/span><\/a><span style=\"font-weight: 400;\"> et r\u00e9servez un bureau ou une salle de r\u00e9union pour la journ\u00e9e.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>La mont\u00e9e en puissance du travail \u00e0 distance n\u00e9cessite de trouver de nouvelles fa\u00e7ons de cr\u00e9er une \u00e9quipe, ce qui ne sera pas une t\u00e2che facile lorsque l&#039;\u00e9quipe est r\u00e9partie sur plusieurs sites. Dans cet article, nous souhaitons vous faire part de quelques outils r\u00e9els que vous pouvez utiliser, ainsi que des activit\u00e9s amusantes et r\u00e9alisables pour les \u00e9quipes virtuelles de tous ...<\/p>","protected":false},"author":7,"featured_media":25533,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[73,69,85,87,237,61,58],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Best remote team building tools &mdash; FLYDESK<\/title>\n<meta name=\"description\" content=\"How to create fun and engaging remote team building activities? Check out our selection of tools and apps to get your remote team closer!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Best remote team building tools &mdash; FLYDESK\" \/>\n<meta property=\"og:description\" content=\"How to create fun and engaging remote team building activities? Check out our selection of tools and apps to get your remote team closer!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/\" \/>\n<meta property=\"og:site_name\" content=\"FLYDESK\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-30T09:02:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-11T03:21:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mlgucbjxeu1m.i.optimole.com\/cb:B7VA.3e989\/w:auto\/h:auto\/q:mauto\/f:best\/ig:avif\/https:\/\/flydesk.com\/wp-content\/uploads\/2020\/11\/daria-nepriakhina-9uEHFjGXnCE-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"FLYDESK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Best remote team building tools &mdash; FLYDESK","description":"Comment cr\u00e9er des activit\u00e9s de team building \u00e0 distance amusantes et engageantes? D\u00e9couvrez notre s\u00e9lection d&#039;outils et d&#039;applications pour rapprocher votre \u00e9quipe distante!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/","og_locale":"fr_FR","og_type":"article","og_title":"Best remote team building tools &mdash; FLYDESK","og_description":"How to create fun and engaging remote team building activities? Check out our selection of tools and apps to get your remote team closer!","og_url":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/","og_site_name":"FLYDESK","article_published_time":"2020-11-30T09:02:21+00:00","article_modified_time":"2023-01-11T03:21:55+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/mlgucbjxeu1m.i.optimole.com\/cb:B7VA.3e989\/w:auto\/h:auto\/q:mauto\/f:best\/ig:avif\/https:\/\/flydesk.com\/wp-content\/uploads\/2020\/11\/daria-nepriakhina-9uEHFjGXnCE-unsplash-scaled.jpg","path":"\/sites\/flydesk.com\/files\/wp-content\/uploads\/2020\/11\/daria-nepriakhina-9uEHFjGXnCE-unsplash-scaled.jpg","size":"full","id":25533,"alt":"","pixels":4369920,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"FLYDESK","Dur\u00e9e de lecture est.":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/flydesk.com\/#organization","name":"FLYDESK","url":"https:\/\/flydesk.com\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/flydesk.com\/#logo","inLanguage":"fr-FR","url":"","contentUrl":"","caption":"FLYDESK"},"image":{"@id":"https:\/\/flydesk.com\/#logo"}},{"@type":"WebSite","@id":"https:\/\/flydesk.com\/#website","url":"https:\/\/flydesk.com\/","name":"FLYDESK","description":"Pilotez votre travail avec style","publisher":{"@id":"https:\/\/flydesk.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flydesk.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/mlgucbjxeu1m.i.optimole.com\/cb:B7VA.3e989\/w:auto\/h:auto\/q:mauto\/f:best\/ig:avif\/https:\/\/flydesk.com\/wp-content\/uploads\/2020\/11\/daria-nepriakhina-9uEHFjGXnCE-unsplash-scaled.jpg","contentUrl":"https:\/\/mlgucbjxeu1m.i.optimole.com\/cb:B7VA.3e989\/w:auto\/h:auto\/q:mauto\/f:best\/ig:avif\/https:\/\/flydesk.com\/wp-content\/uploads\/2020\/11\/daria-nepriakhina-9uEHFjGXnCE-unsplash-scaled.jpg","width":2560,"height":1707,"caption":"Best remote team building tools"},{"@type":"WebPage","@id":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/#webpage","url":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/","name":"Best remote team building tools &mdash; FLYDESK","isPartOf":{"@id":"https:\/\/flydesk.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/#primaryimage"},"datePublished":"2020-11-30T09:02:21+00:00","dateModified":"2023-01-11T03:21:55+00:00","description":"Comment cr\u00e9er des activit\u00e9s de team building \u00e0 distance amusantes et engageantes? D\u00e9couvrez notre s\u00e9lection d&#039;outils et d&#039;applications pour rapprocher votre \u00e9quipe distante!","breadcrumb":{"@id":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flydesk.com\/"},{"@type":"ListItem","position":2,"name":"Best remote team building tools"}]},{"@type":"Article","@id":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/#article","isPartOf":{"@id":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/#webpage"},"author":{"@id":"https:\/\/flydesk.com\/#\/schema\/person\/7ee7a2a81022450574cd387741e21a36"},"headline":"Best remote team building tools","datePublished":"2020-11-30T09:02:21+00:00","dateModified":"2023-01-11T03:21:55+00:00","mainEntityOfPage":{"@id":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/#webpage"},"wordCount":1424,"commentCount":0,"publisher":{"@id":"https:\/\/flydesk.com\/#organization"},"image":{"@id":"https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/#primaryimage"},"thumbnailUrl":"https:\/\/mlgucbjxeu1m.i.optimole.com\/cb:B7VA.3e989\/w:auto\/h:auto\/q:mauto\/f:best\/ig:avif\/https:\/\/flydesk.com\/wp-content\/uploads\/2020\/11\/daria-nepriakhina-9uEHFjGXnCE-unsplash-scaled.jpg","keywords":["Applications","Collaboration","Remote collaboration","Remote management","Remote work","Team culture","Work from home"],"articleSection":["Management"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/flydesk.com\/fr\/insights\/best-remote-team-building-tools\/#respond"]}]},{"@type":"Person","@id":"https:\/\/flydesk.com\/#\/schema\/person\/7ee7a2a81022450574cd387741e21a36","name":"FLYDESK","image":{"@type":"ImageObject","@id":"https:\/\/flydesk.com\/#personlogo","inLanguage":"fr-FR","url":"https:\/\/secure.gravatar.com\/avatar\/01b1d9bab372998a16bd3550155069db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01b1d9bab372998a16bd3550155069db?s=96&d=mm&r=g","caption":"FLYDESK"}}]}},"_links":{"self":[{"href":"https:\/\/flydesk.com\/fr\/wp-json\/wp\/v2\/posts\/25528"}],"collection":[{"href":"https:\/\/flydesk.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flydesk.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flydesk.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/flydesk.com\/fr\/wp-json\/wp\/v2\/comments?post=25528"}],"version-history":[{"count":0,"href":"https:\/\/flydesk.com\/fr\/wp-json\/wp\/v2\/posts\/25528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flydesk.com\/fr\/wp-json\/wp\/v2\/media\/25533"}],"wp:attachment":[{"href":"https:\/\/flydesk.com\/fr\/wp-json\/wp\/v2\/media?parent=25528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flydesk.com\/fr\/wp-json\/wp\/v2\/categories?post=25528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flydesk.com\/fr\/wp-json\/wp\/v2\/tags?post=25528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}